{"id":139268,"date":"2026-05-11T03:03:36","date_gmt":"2026-05-11T01:03:36","guid":{"rendered":"https:\/\/news.abusizz.ch\/lohn-gegen-sinn-sie-wechselten-in-einen-schlechter-bezahlten-job-und-bereuen-nichts\/"},"modified":"2026-05-11T03:03:36","modified_gmt":"2026-05-11T01:03:36","slug":"lohn-gegen-sinn-sie-wechselten-in-einen-schlechter-bezahlten-job-und-bereuen-nichts","status":"publish","type":"post","link":"https:\/\/news.abusizz.ch\/en\/lohn-gegen-sinn-sie-wechselten-in-einen-schlechter-bezahlten-job-und-bereuen-nichts\/","title":{"rendered":"Lohn gegen Sinn: Sie wechselten in einen schlechter bezahlten Job \u2013 und bereuen nichts"},"content":{"rendered":"<div>Eine Finanzchefin betreibt eine Bootsbeiz, eine HR-Chefin macht ein Praktikum und ein Banker wird Lehrer: Drei Menschen erz\u00e4hlen von ihrer zweiten Karriere, die nur auf den ersten Blick ein Schritt zur\u00fcck war.<\/div>","protected":false},"excerpt":{"rendered":"<p>Eine Finanzchefin betreibt eine Bootsbeiz, eine HR-Chefin macht ein Praktikum und ein Banker wird Lehrer: Drei Menschen erz\u00e4hlen von ihrer zweiten Karriere, die nur auf den ersten Blick ein Schritt zur\u00fcck war.<\/p>","protected":false},"author":11,"featured_media":139269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,1],"tags":[],"class_list":["post-139268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ta-wirtschaft","category-topstory"],"_links":{"self":[{"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/posts\/139268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/comments?post=139268"}],"version-history":[{"count":0,"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/posts\/139268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/media\/139269"}],"wp:attachment":[{"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/media?parent=139268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/categories?post=139268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.abusizz.ch\/en\/wp-json\/wp\/v2\/tags?post=139268"}],"curies":[{"name":"what","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}