{"id":139343,"date":"2026-05-13T03:03:59","date_gmt":"2026-05-13T01:03:59","guid":{"rendered":"https:\/\/news.abusizz.ch\/interview-wenn-es-so-weitergeht-stirbt-die-gesamte-menschheit-aus-wir-weissen-europaeer-werden-zu-den-ersten-gehoeren-sagt-der-demograf\/"},"modified":"2026-05-13T03:03:59","modified_gmt":"2026-05-13T01:03:59","slug":"interview-wenn-es-so-weitergeht-stirbt-die-gesamte-menschheit-aus-wir-weissen-europaeer-werden-zu-den-ersten-gehoeren-sagt-der-demograf","status":"publish","type":"post","link":"https:\/\/news.abusizz.ch\/fr\/interview-wenn-es-so-weitergeht-stirbt-die-gesamte-menschheit-aus-wir-weissen-europaeer-werden-zu-den-ersten-gehoeren-sagt-der-demograf\/","title":{"rendered":"INTERVIEW &#8211; \u00abWenn es so weitergeht, stirbt die gesamte Menschheit aus. Wir weissen Europ\u00e4er werden zu den Ersten geh\u00f6ren\u00bb, sagt der Demograf"},"content":{"rendered":"<div>Laut Paul Morland steuert unsere Gesellschaft wegen der tiefen Geburtenrate auf eine Katastrophe zu. Eine solche Situation habe es in der Menschheitsgeschichte noch nie gegeben, sagt er im Gespr\u00e4ch.<\/div>","protected":false},"excerpt":{"rendered":"<p>Laut Paul Morland steuert unsere Gesellschaft wegen der tiefen Geburtenrate auf eine Katastrophe zu. Eine solche Situation habe es in der Menschheitsgeschichte noch nie gegeben, sagt er im Gespr\u00e4ch.<\/p>","protected":false},"author":11,"featured_media":139344,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[26,1],"tags":[],"class_list":["post-139343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nzz-kultur","category-topstory"],"_links":{"self":[{"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/posts\/139343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/comments?post=139343"}],"version-history":[{"count":0,"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/posts\/139343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/media\/139344"}],"wp:attachment":[{"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/media?parent=139343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/categories?post=139343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.abusizz.ch\/fr\/wp-json\/wp\/v2\/tags?post=139343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}