{"id":139260,"date":"2026-05-11T03:01:29","date_gmt":"2026-05-11T01:01:29","guid":{"rendered":"https:\/\/news.abusizz.ch\/iran-reagiert-auf-amerikanischen-vorschlag-zur-beendigung-des-krieges-trump-nennt-antwort-voellig-inakzeptabel\/"},"modified":"2026-05-11T03:01:29","modified_gmt":"2026-05-11T01:01:29","slug":"iran-reagiert-auf-amerikanischen-vorschlag-zur-beendigung-des-krieges-trump-nennt-antwort-voellig-inakzeptabel","status":"publish","type":"post","link":"https:\/\/news.abusizz.ch\/it\/iran-reagiert-auf-amerikanischen-vorschlag-zur-beendigung-des-krieges-trump-nennt-antwort-voellig-inakzeptabel\/","title":{"rendered":"Iran reagiert auf amerikanischen Vorschlag zur Beendigung des Krieges \u2013 Trump nennt Antwort \u00abv\u00f6llig inakzeptabel\u00bb"},"content":{"rendered":"<div>Drei Tage nach Ende der Frist antwortet das iranische Regime laut Staatsmedien auf den Entwurf aus Washington. US-Pr\u00e4sident Trump zeigt sich \u00fcber die Antwort Teherans auf den US-Friedensvorschlag emp\u00f6rt.<\/div>","protected":false},"excerpt":{"rendered":"<p>Drei Tage nach Ende der Frist antwortet das iranische Regime laut Staatsmedien auf den Entwurf aus Washington. US-Pr\u00e4sident Trump zeigt sich \u00fcber die Antwort Teherans auf den US-Friedensvorschlag emp\u00f6rt.<\/p>","protected":false},"author":11,"featured_media":139261,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14,1],"tags":[],"class_list":["post-139260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nzz","category-topstory"],"_links":{"self":[{"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/posts\/139260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/comments?post=139260"}],"version-history":[{"count":0,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/posts\/139260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/media\/139261"}],"wp:attachment":[{"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/media?parent=139260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/categories?post=139260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/tags?post=139260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}