{"id":139270,"date":"2026-05-11T03:03:41","date_gmt":"2026-05-11T01:03:41","guid":{"rendered":"https:\/\/news.abusizz.ch\/interview-mit-job-profilerin-viele-suchen-einen-beruf-den-sie-bis-65-durchhalten-koennen\/"},"modified":"2026-05-11T03:03:41","modified_gmt":"2026-05-11T01:03:41","slug":"interview-mit-job-profilerin-viele-suchen-einen-beruf-den-sie-bis-65-durchhalten-koennen","status":"publish","type":"post","link":"https:\/\/news.abusizz.ch\/it\/interview-mit-job-profilerin-viele-suchen-einen-beruf-den-sie-bis-65-durchhalten-koennen\/","title":{"rendered":"Interview mit Job-Profilerin: \u00abViele suchen einen Beruf, den sie bis 65 durchhalten k\u00f6nnen\u00bb"},"content":{"rendered":"<div>Katrin Wilkens hat rund 2\u2019500 Menschen geholfen, den passenden Job zu finden. Sie erkl\u00e4rt, wann eine radikale Ver\u00e4nderung unumg\u00e4nglich ist \u2013 und nennt f\u00fcnf Fragen, die man sich vor einem Wechsel stellen sollte.<\/div>","protected":false},"excerpt":{"rendered":"<p>Katrin Wilkens hat rund 2\u2019500 Menschen geholfen, den passenden Job zu finden. Sie erkl\u00e4rt, wann eine radikale Ver\u00e4nderung unumg\u00e4nglich ist \u2013 und nennt f\u00fcnf Fragen, die man sich vor einem Wechsel stellen sollte.<\/p>","protected":false},"author":11,"featured_media":139271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,1],"tags":[],"class_list":["post-139270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ta-wirtschaft","category-topstory"],"_links":{"self":[{"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/posts\/139270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/comments?post=139270"}],"version-history":[{"count":0,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/posts\/139270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/media\/139271"}],"wp:attachment":[{"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/media?parent=139270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/categories?post=139270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.abusizz.ch\/it\/wp-json\/wp\/v2\/tags?post=139270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}